{"id":518,"date":"2024-03-15T23:46:47","date_gmt":"2024-03-15T20:16:47","guid":{"rendered":"https:\/\/dentalifeco.com\/en\/?page_id=518"},"modified":"2024-05-27T13:20:08","modified_gmt":"2024-05-27T09:50:08","slug":"dentalife-sport-toothbrush","status":"publish","type":"page","link":"https:\/\/dentalifeco.com\/en\/dentalife-sport-toothbrush\/","title":{"rendered":"Dentalife Sport"},"content":{"rendered":"<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-572737926\">\n\n\t<div id=\"col-247631118\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1810770187\" >\n    <div class=\"slider slider-type-fade slider-nav-simple slider-nav-normal slider-nav-dark slider-nav-outside slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1340020744\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1340020744 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1688140456\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1688140456 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_755424324\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_755424324 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1075479514\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1075479514 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1949194635\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1949194635 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-435797727\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-435797727 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\n  \n    <div class=\"row hide-for-medium large-columns-5 medium-columns-3 small-columns-2 row-xsmall row-full-width\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"633,631,632,630,634\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-02.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"633,631,632,630,634\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-04.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"633,631,632,630,634\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-03.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"633,631,632,630,634\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-05.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"633,631,632,630,634\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-01.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-247631118 > .col-inner {\n  padding: 20px 10px 20px 10px;\n}\n@media (min-width:550px) {\n  #col-247631118 > .col-inner {\n    padding: 50px 20px 50px 20px;\n  }\n}\n@media (min-width:850px) {\n  #col-247631118 > .col-inner {\n    padding: 80px 200px 100px 200px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-782748087\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(247, 247, 247);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1965774818\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"915\" height=\"183\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-logo.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-logo.png 915w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-logo-300x60.png 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/sport-logo-768x154.png 768w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1965774818 {\n  width: 40%;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h1 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Dentalife sport<\/span><b><\/b><\/h1><\/div>\n<p>However, the condition of the front teeth is usually better. When chewing and eating, the main effort is on the rear teeth. Additionally, the front teeth are much easier to clean when brushing.<\/p>\n<p>Therefore, it&#8217;s important to take extra care of our back teeth by using a standard and suitable toothbrush to clean them thoroughly.<\/p>\n<p>The Dental Life Sports toothbrush is one of the best options! The long fibers at the tip of this toothbrush help clean the back teeth effectively. The angular arrangement of the fibers ensures complete cleaning of the interdental spaces and tooth surfaces. The completely round and silky fibers protect the gums and tooth enamel. One unique feature of Dentallife Sport is the cushioned design around the brush head, which minimizes pressure on the gums.<\/p>\n<p>Finally, the bulky handle of Dentallife Sport makes it easier to maneuver. All these features combine to make the Dentallife Sport toothbrush irresistible.<\/p>\n<div class=\"row\"  id=\"row-1598249042\">\n\n\t<div id=\"col-1957403347\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><span style=\"font-size: 75%;\">100% Rounded Bristles<\/span><\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1047616124\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/ergonomic-toothbrush.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/ergonomic-toothbrush.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/ergonomic-toothbrush-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><span style=\"font-size: 75%;\">Ergonomic Handle<\/span><\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1402526310\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><span style=\"font-size: 75%;\">Silk Fibers<\/span><\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-782748087 > .col-inner {\n  padding: 50px 10px 50px 10px;\n}\n@media (min-width:550px) {\n  #col-782748087 > .col-inner {\n    padding: 50px 20px 50px 50px;\n  }\n}\n@media (min-width:850px) {\n  #col-782748087 > .col-inner {\n    padding: 100px 120px 100px 120px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-518","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/comments?post=518"}],"version-history":[{"count":18,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/518\/revisions"}],"predecessor-version":[{"id":1037,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/518\/revisions\/1037"}],"wp:attachment":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/media?parent=518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}