{"id":506,"date":"2024-03-15T23:34:18","date_gmt":"2024-03-15T20:04:18","guid":{"rendered":"https:\/\/dentalifeco.com\/en\/?page_id=506"},"modified":"2024-05-27T11:12:25","modified_gmt":"2024-05-27T07:42:25","slug":"dentalife-quantum-toothbrush","status":"publish","type":"page","link":"https:\/\/dentalifeco.com\/en\/dentalife-quantum-toothbrush\/","title":{"rendered":"Dentalife Quantum"},"content":{"rendered":"<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-547065638\">\n\n\t<div id=\"col-213610573\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1723904485\" >\n    <div class=\"slider slider-type-fade slider-nav-simple slider-nav-normal slider-nav-dark slider-nav-outside slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_826590102\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_826590102 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_414754785\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_414754785 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_395512965\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_395512965 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_104311200\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_104311200 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1664414234\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"855\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02.png 623w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02-219x300.png 219w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1664414234 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-1978623822\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1978623822 {\n  padding-top: 100px;\n}\n<\/style>\n\t<\/div>\n\t\n\n  \n    <div class=\"row hide-for-medium large-columns-5 medium-columns-3 small-columns-2 row-xsmall row-full-width\" >\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"806,805,807,808,809\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-05.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"806,805,807,808,809\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-06.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"806,805,807,808,809\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-04.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"806,805,807,808,809\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-03.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"219\" height=\"300\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02-219x300.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"806,805,807,808,809\" style=\"none\" lightbox_image_size=\"original\" col_spacing=\"xsmall\" columns=\"5\" visibility=\"hide-for-medium\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02-219x300.png 219w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-02.png 623w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-213610573 > .col-inner {\n  padding: 20px 10px 20px 10px;\n}\n@media (min-width:550px) {\n  #col-213610573 > .col-inner {\n    padding: 50px 20px 50px 20px;\n  }\n}\n@media (min-width:850px) {\n  #col-213610573 > .col-inner {\n    padding: 80px 200px 100px 200px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1515769187\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(247, 247, 247);\" >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_872680135\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"795\" height=\"193\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-01.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-01.png 795w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-01-300x73.png 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/q-01-768x186.png 768w\" sizes=\"auto, (max-width: 795px) 100vw, 795px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_872680135 {\n  width: 52%;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"container section-title-container\" ><h1 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Dentalife Quantum<\/span><b><\/b><\/h1><\/div>\n<div>Some people prefer to choose a suitable and standard toothbrush once and stick with it every time they buy. They seek a toothbrush that boasts all the features of a first-class cleaner and is made with the latest technology. The Dentallife Quantum toothbrush is designed precisely for these individuals.<\/div>\n<div>\u00a0<\/div>\n<div>This toothbrush offers features such as:<\/div>\n<div>\u00a0<\/div>\n<ul>\n<li>A fully rounded fiber head for comprehensive protection of gums and tooth enamel.<\/li>\n<li>A flexible, two-piece brush to reduce pressure on the gums and ensure easy access to interdental areas.<\/li>\n<li>A standard and unique head and handle design.<\/li>\n<\/ul>\n<div>The Dentallife Quantum is a suitable choice for many people. If you don&#8217;t have very sensitive teeth and are looking for a reliable toothbrush for worry-free and consistent shopping, Dentallife Quantum is an excellent choice for you.<\/div>\n<div class=\"row\"  id=\"row-1526954276\">\n\n\t<div id=\"col-1294429076\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><span style=\"font-size: 75%;\">100% Rounded Bristles<\/span><\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1068009885\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/ergonomic-toothbrush.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/ergonomic-toothbrush.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/ergonomic-toothbrush-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><span style=\"font-size: 75%;\">Ergonomic Handle<\/span><\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1630938521\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<p><strong><span style=\"font-size: 75%;\">Silk Fibers<\/span><\/strong><\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1515769187 > .col-inner {\n  padding: 50px 10px 50px 10px;\n}\n@media (min-width:550px) {\n  #col-1515769187 > .col-inner {\n    padding: 50px 20px 50px 50px;\n  }\n}\n@media (min-width:850px) {\n  #col-1515769187 > .col-inner {\n    padding: 100px 120px 100px 120px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-506","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":12,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/506\/revisions"}],"predecessor-version":[{"id":1021,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/506\/revisions\/1021"}],"wp:attachment":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/media?parent=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}