{"id":22,"date":"2024-02-13T19:37:59","date_gmt":"2024-02-13T16:07:59","guid":{"rendered":"https:\/\/dentalifeco.com\/en\/?page_id=22"},"modified":"2024-06-01T13:32:03","modified_gmt":"2024-06-01T10:02:03","slug":"home","status":"publish","type":"page","link":"https:\/\/dentalifeco.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\n\t\t\t<!-- START New Slider REVOLUTION SLIDER 6.6.20 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_3_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_3_1\" style=\"\" data-version=\"6.6.20\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-8\" data-title=\"Slide\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dentalifeco.com\/en\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"full-screen-layer-04\" width=\"2000\" height=\"887\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/04\/full-screen-layer-04.jpg\" data-bg=\"p:left top;\" data-panzoom=\"d:10000;ss:100;se:115%;\" data-no-retina>\n<!--\t\t\t\t\t\t--><rs-zone id=\"rrzb_8\" class=\"rev_row_zone_bottom\" style=\"z-index: 4;\"><!--\n\n\t\t\t\t\t\t\t\t--><rs-row\n\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-8-layer-0\" \n\t\t\t\t\t\t\t\t\tdata-type=\"row\"\n\t\t\t\t\t\t\t\t\tdata-xy=\"xo:50px;yo:352px;\"\n\t\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;sA:9000;\"\n\t\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t\t><!--\n\t\t\t\t\t\t\t\t\t--><rs-column\n\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-8-layer-1\" \n\t\t\t\t\t\t\t\t\t\tdata-type=\"column\"\n\t\t\t\t\t\t\t\t\t\tdata-xy=\"xo:50px;yo:352px;\"\n\t\t\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\t\t\tdata-column=\"w:50%;\"\n\t\t\t\t\t\t\t\t\t\tdata-margin=\"r:100,100,50,10;l:100,100,50,10;\"\n\t\t\t\t\t\t\t\t\t\tdata-padding=\"t:50;r:50;b:50;l:50;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;sA:9000;\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:rgba(255,255,255,0.8);width:100%;\"\n\t\t\t\t\t\t\t\t\t><!--\n\t\t\t\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-8-layer-4\" \n\t\t\t\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#ff3a2d\"\n\t\t\t\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\t\t\t\tdata-xy=\"\"\n\t\t\t\t\t\t\t\t\t\t\tdata-pos=\"r\"\n\t\t\t\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:32,32,28,25;l:55,55,40,30;fw:600;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50,-50,-25,-15;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_1=\"sp:1000;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"y:-50,-50,-25,-15;o:0;st:w;sp:1000;sR:8000;\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:7;font-family:'Montserrat';\"\n\t\t\t\t\t\t\t\t\t\t>With Dentalife \n\t\t\t\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-8-layer-3\" \n\t\t\t\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#420d09\"\n\t\t\t\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\t\t\t\tdata-xy=\"\"\n\t\t\t\t\t\t\t\t\t\t\tdata-pos=\"r\"\n\t\t\t\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:26,26,25,20;l:40,40,35,30;fw:600;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"x:50,50,25,15;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_1=\"st:430;sp:1000;sR:430;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"x:-50,-50,-25,-15;o:0;st:w;sp:1000;sR:7570;\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Montserrat';\"\n\t\t\t\t\t\t\t\t\t\t>Make family's brushing as a happy daily activity. \n\t\t\t\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t\t\t\t\t--><\/rs-column><!--\n\n\t\t\t\t\t\t\t\t\t--><rs-column\n\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-8-layer-2\" \n\t\t\t\t\t\t\t\t\t\tdata-type=\"column\"\n\t\t\t\t\t\t\t\t\t\tdata-xy=\"xo:50px;yo:352px;\"\n\t\t\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\t\t\tdata-column=\"w:50%;\"\n\t\t\t\t\t\t\t\t\t\tdata-padding=\"t:10;r:10;b:10;l:10;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;sA:9000;\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:6;width:100%;\"\n\t\t\t\t\t\t\t\t\t><!--\t\t\t\t\t\t\t\t\t--><\/rs-column><!--\n\t\t\t\t\t\t\t\t--><\/rs-row><!--\n\t\t\t\t\t\t\t--><\/rs-zone><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-11\" data-title=\"Slide\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/dentalifeco.com\/en\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"Slider-back\" width=\"2000\" height=\"867\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/03\/Slider-back.jpg\" data-bg=\"p:left top;\" data-panzoom=\"d:10000;ss:100;se:115%;\" data-no-retina>\n<!--\t\t\t\t\t\t--><rs-zone id=\"rrzb_11\" class=\"rev_row_zone_bottom\" style=\"z-index: 4;\"><!--\n\n\t\t\t\t\t\t\t\t--><rs-row\n\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-11-layer-0\" \n\t\t\t\t\t\t\t\t\tdata-type=\"row\"\n\t\t\t\t\t\t\t\t\tdata-xy=\"xo:50px;yo:352px;\"\n\t\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;sA:9000;\"\n\t\t\t\t\t\t\t\t\tstyle=\"z-index:6;\"\n\t\t\t\t\t\t\t\t><!--\n\t\t\t\t\t\t\t\t\t--><rs-column\n\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-11-layer-1\" \n\t\t\t\t\t\t\t\t\t\tdata-type=\"column\"\n\t\t\t\t\t\t\t\t\t\tdata-xy=\"xo:50px;yo:352px;\"\n\t\t\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\t\t\tdata-column=\"w:50%;\"\n\t\t\t\t\t\t\t\t\t\tdata-margin=\"r:100,100,50,10;l:100,100,50,10;\"\n\t\t\t\t\t\t\t\t\t\tdata-padding=\"t:50;r:50;b:50;l:50;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;sA:9000;\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:rgba(255,255,255,0.8);width:100%;\"\n\t\t\t\t\t\t\t\t\t><!--\n\t\t\t\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-11-layer-4\" \n\t\t\t\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#ff3a2d\"\n\t\t\t\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\t\t\t\tdata-xy=\"\"\n\t\t\t\t\t\t\t\t\t\t\tdata-pos=\"r\"\n\t\t\t\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:32,32,28,25;l:55,55,40,30;fw:600;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"y:-50,-50,-25,-15;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_1=\"sp:1000;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"y:-50,-50,-25,-15;o:0;st:w;sp:1000;sR:8000;\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:7;font-family:'Montserrat';\"\n\t\t\t\t\t\t\t\t\t\t>With Dentalife \n\t\t\t\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-11-layer-3\" \n\t\t\t\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\t\t\t\tdata-color=\"#420d09\"\n\t\t\t\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\t\t\t\tdata-xy=\"\"\n\t\t\t\t\t\t\t\t\t\t\tdata-pos=\"r\"\n\t\t\t\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:26,26,25,20;l:40,40,35,30;fw:600;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"x:50,50,25,15;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_1=\"st:430;sp:1000;sR:430;\"\n\t\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"x:-50,-50,-25,-15;o:0;st:w;sp:1000;sR:7570;\"\n\t\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:'Montserrat';\"\n\t\t\t\t\t\t\t\t\t\t>Take Care of your Teeth with a Toothbrush trusted by Dentists. \n\t\t\t\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t\t\t\t\t--><\/rs-column><!--\n\n\t\t\t\t\t\t\t\t\t--><rs-column\n\t\t\t\t\t\t\t\t\t\tid=\"slider-3-slide-11-layer-2\" \n\t\t\t\t\t\t\t\t\t\tdata-type=\"column\"\n\t\t\t\t\t\t\t\t\t\tdata-xy=\"xo:50px;yo:352px;\"\n\t\t\t\t\t\t\t\t\t\tdata-rsp_bd=\"off\"\n\t\t\t\t\t\t\t\t\t\tdata-column=\"w:50%;\"\n\t\t\t\t\t\t\t\t\t\tdata-padding=\"t:10;r:10;b:10;l:10;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_0=\"o:1;\"\n\t\t\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;sR:8700;sA:9000;\"\n\t\t\t\t\t\t\t\t\t\tstyle=\"z-index:6;width:100%;\"\n\t\t\t\t\t\t\t\t\t><!--\t\t\t\t\t\t\t\t\t--><\/rs-column><!--\n\t\t\t\t\t\t\t\t--><\/rs-row><!--\n\t\t\t\t\t\t\t--><\/rs-zone><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-3-slide-3-layer-6\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,l;xo:-126px,-126px,-263px,60px;y:m,m,m,b;yo:64px,64px,225px,210px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:50;l:50;\"\n\t\t\t\t\t\t\t\tdata-vbility=\"t,t,f,f\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:jumptoslide;slide:previous;'\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:7;background-color:rgba(196,35,41,0.5);font-family:'Roboto';\"\n\t\t\t\t\t\t\t><i class=\"material-icons\">keyboard_arrow_right<\/i> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-3-slide-3-layer-7\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer-static\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c,c,c,l;xo:-176px,-176px,-314px,10px;y:m,m,m,b;yo:64px,64px,225px,210px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:50;l:50;\"\n\t\t\t\t\t\t\t\tdata-vbility=\"t,t,f,f\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:jumptoslide;slide:next;'\n\t\t\t\t\t\t\t\tdata-onslides=\"s:1;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(196,35,41,0.5);font-family:'Roboto';\"\n\t\t\t\t\t\t\t><i class=\"material-icons\">keyboard_arrow_left<\/i> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_3_1',rl:[1240,1240,778,480],el:[650,650,960,720],gw:[1500,1500,778,480],gh:[650,650,960,720],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider31\"]!==undefined) {window.RS_MODULES.modules[\"revslider31\"].once = false;window.revapi3 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-995240144\">\n\n\t<div id=\"col-1284021839\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h1 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Why Dentalife?<\/span><b><\/b><\/h1><\/div>\n<p><strong>We expect a toothbrush to:<\/strong><br \/>With soft and silky fibers;<br \/>With an attractive and practical design for its head and body;<br \/>Introduce a special toothbrush tailored to the types of teeth and specific conditions of each individual;<br \/>Being produced with the latest and most advanced technology in the world;<br \/>Dentallife possesses all of these features.<\/p>\n<div class=\"row row-small align-middle align-center\"  id=\"row-890140507\">\n\n\t<div id=\"col-2074698397\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-technology-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-technology-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-technology-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Produced with Global Technology<\/h5>\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2074698397 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1860279135\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left is-small\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-toothbrush-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">100% rounded brush bristles<\/h5>\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1860279135 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1443100274\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left is-small\"  style=\"margin:0px 0px 0px 0px;\">\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 55px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"179\" height=\"179\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1.png 179w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/00-butterfly-1-150x150.png 150w\" sizes=\"auto, (max-width: 179px) 100vw, 179px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t<h5 class=\"uppercase\">Silk fibers are Teeth Friendly<\/h5>\t\t\t\t\t\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1443100274 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t<div id=\"gap-773089368\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-773089368 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"https:\/\/dentalifeco.com\/en\/about-dentalife\/\" class=\"button primary is-small lowercase\"  >\n    <span>Read More<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1284021839 > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n@media (min-width:550px) {\n  #col-1284021839 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1284021839 > .col-inner {\n    padding: 60px 50px 60px 270px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1492144431\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_189873249\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" style=\"margin:0px 0px 0px 0px;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1115\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/fusion-orange-1.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/fusion-orange-1.png 800w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/fusion-orange-1-215x300.png 215w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/fusion-orange-1-735x1024.png 735w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/fusion-orange-1-768x1070.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_189873249 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1492144431 > .col-inner {\n  padding: 20px 20px 20px 20px;\n}\n@media (min-width:550px) {\n  #col-1492144431 > .col-inner {\n    padding: 25px 25px 34px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1492144431 > .col-inner {\n    padding: 150px 260px 0px 130px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<style>\n#row-995240144 > .col > .col-inner {\n  background-color: rgb(251, 251, 251);\n}\n<\/style>\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-683059748\" >\n    <div class=\"slider slider-type-fade slider-nav-dots-dashes slider-nav-circle slider-nav-large slider-nav-dark slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": false,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": false,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-1510039159\">\n\n\t<div id=\"col-1634881434\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1869072566\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1593\" height=\"1062\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/man-with-toothbrush-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/man-with-toothbrush-1.jpg 1593w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/man-with-toothbrush-1-300x200.jpg 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/man-with-toothbrush-1-1024x683.jpg 1024w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/man-with-toothbrush-1-768x512.jpg 768w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/man-with-toothbrush-1-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1593px) 100vw, 1593px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1869072566 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1634881434 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-1634881434 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1634881434 > .col-inner {\n    padding: 150px 30px 100px 270px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-20716950\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Toothbrushes for adults<\/span><b><\/b><\/h3><\/div>\n<p style=\"text-align: justify;\">Adults encounter a range of challenges when it comes to oral hygiene: some deal with sensitive teeth and delicate gums, while others struggle with plaque buildup. Many seek a toothbrush with a soft-headed design suitable for daily use. Dentallife offers a variety of adult toothbrushes that cater to these diverse needs and preferences.<\/p>\n<a href=\"https:\/\/dentalifeco.com\/en\/dentalife-adult-tothbrush\/\" class=\"button primary is-small lowercase\"  >\n    <span>Read More<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-20716950 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-20716950 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-20716950 > .col-inner {\n    padding: 180px 270px 100px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-864418689\">\n\n\t<div id=\"col-1201151628\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1146024347\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1595\" height=\"1063\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-toothbrush.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-toothbrush.jpg 1595w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-toothbrush-300x200.jpg 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-toothbrush-1024x682.jpg 1024w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-toothbrush-768x512.jpg 768w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-toothbrush-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1595px) 100vw, 1595px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1146024347 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1201151628 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-1201151628 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1201151628 > .col-inner {\n    padding: 150px 30px 100px 270px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1025158530\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Orthodontic toothbrush<\/span><b><\/b><\/h3><\/div>\n<p style=\"text-align: left;\">Individuals undergoing orthodontic treatment face challenging months ahead, as food remnants and dental plaque easily accumulate around braces. In this battle, Dentallife orthodontic toothbrushes serve as reliable warriors, effectively removing plaque throughout the entire treatment period.<\/p>\n<a href=\"https:\/\/dentalifeco.com\/en\/dentalife-orthodontic-toothbrush\/\" class=\"button primary is-small lowercase\"  >\n    <span>Read More<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1025158530 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-1025158530 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1025158530 > .col-inner {\n    padding: 180px 270px 100px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-2068810520\">\n\n\t<div id=\"col-1812764902\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1783717095\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1591\" height=\"1061\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-white-toothbrush.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-white-toothbrush.jpg 1591w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-white-toothbrush-300x200.jpg 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-white-toothbrush-1024x683.jpg 1024w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-white-toothbrush-768x512.jpg 768w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/woman-white-toothbrush-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1591px) 100vw, 1591px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1783717095 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1812764902 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-1812764902 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1812764902 > .col-inner {\n    padding: 150px 30px 100px 270px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-100593025\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Teeth whitening toothbrushes<\/span><b><\/b><\/h3><\/div>\n<p style=\"text-align: left;\">Many individuals regularly indulge in habits like smoking, drinking tea or coffee, and consuming various foods without proper dental care. Consequently, they often develop unsightly stains on their teeth and seek a solution. Dentallife offers whitening toothbrushes equipped with compact and dense fibers, providing the ideal solution for those seeking to address such discoloration.<\/p>\n<a href=\"https:\/\/dentalifeco.com\/en\/teeth-whitening-toothbrushes\/\" class=\"button success is-small lowercase\"  >\n    <span>Read More<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-100593025 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-100593025 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-100593025 > .col-inner {\n    padding: 180px 270px 100px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-349951367\">\n\n\t<div id=\"col-2031854337\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_438497797\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1593\" height=\"1065\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Child-Toothbrush.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Child-Toothbrush.jpg 1593w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Child-Toothbrush-300x201.jpg 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Child-Toothbrush-1024x685.jpg 1024w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Child-Toothbrush-768x513.jpg 768w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Child-Toothbrush-1536x1027.jpg 1536w\" sizes=\"auto, (max-width: 1593px) 100vw, 1593px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_438497797 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2031854337 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-2031854337 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-2031854337 > .col-inner {\n    padding: 150px 30px 100px 270px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1572063371\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Toothbrush for children<\/span><b><\/b><\/h3><\/div>\n<p style=\"text-align: left;\">Would you like your child to develop the habit of brushing their teeth independently? Providing a beautiful, colorful, and soft toothbrush with a small, round head could suffice. With patience, foster a lasting bond between them and their toothbrush. Dentallife is here to support you in this unique yet rewarding journey.<\/p>\n<a href=\"https:\/\/dentalifeco.com\/en\/dentalife-kids-toothbrush\/\" class=\"button primary is-small lowercase\"  >\n    <span>Read More<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1572063371 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-1572063371 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1572063371 > .col-inner {\n    padding: 180px 270px 100px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-373471374\">\n\n\t<div id=\"col-199926351\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_619699108\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1593\" height=\"1064\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/senior-with-toothbrush.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/senior-with-toothbrush.jpg 1593w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/senior-with-toothbrush-300x200.jpg 300w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/senior-with-toothbrush-1024x684.jpg 1024w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/senior-with-toothbrush-768x513.jpg 768w, https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/senior-with-toothbrush-1536x1026.jpg 1536w\" sizes=\"auto, (max-width: 1593px) 100vw, 1593px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_619699108 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-199926351 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-199926351 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-199926351 > .col-inner {\n    padding: 150px 30px 100px 270px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1707908278\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Toothbrush for sensitive teeth<\/span><b><\/b><\/h3><\/div>\n<p style=\"text-align: left;\">It&#8217;s not just about using soft toothbrushes to address the issue of sensitive teeth and gums. Along with soft and silky fibers, an effective toothbrush should also feature a flexible, two-piece brush with a completely rounded end and a specially designed handle. Dentallife&#8217;s toothbrushes meticulously incorporate all these essential elements to ensure thorough care and attention to detail.<\/p>\n<a href=\"https:\/\/dentalifeco.com\/en\/dentalfe-sensetive-toothbrush\/\" class=\"button alert is-small lowercase\"  >\n    <span>Read More<\/span>\n  <\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1707908278 > .col-inner {\n  padding: 25px 25px 25px 25px;\n}\n@media (min-width:550px) {\n  #col-1707908278 > .col-inner {\n    padding: 25px 25px 25px 25px;\n  }\n}\n@media (min-width:850px) {\n  #col-1707908278 > .col-inner {\n    padding: 180px 270px 100px 50px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t<div id=\"gap-1891274379\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1891274379 {\n  padding-top: 80px;\n}\n<\/style>\n\t<\/div>\n\t\n\n  \n    <div class=\"row large-columns-7 medium-columns-5 small-columns-3 row-large slider row-slider slider-nav-reveal\"  data-flickity-options='{\"imagesLoaded\": true, \"groupCells\": \"100%\", \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : false}' >\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/certificate-logos_05-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/certificate-logos_05-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/FDA-Logo-1-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/FDA-Logo-1-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/IDA-Logo-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/IDA-Logo-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/IFDA-Logo-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/IFDA-Logo-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/iso-logo-01-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/iso-logo-01-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/iso-logo-02-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/iso-logo-02-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/iso-logo-03-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/iso-logo-03-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/sgi-logo-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/sgi-logo-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n            <a class=\"image-lightbox lightbox-gallery\" href=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Standard-Iran-Logo-300x283-1.png\" title=\"\">            <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"283\" src=\"https:\/\/dentalifeco.com\/en\/wp-content\/uploads\/2024\/02\/Standard-Iran-Logo-300x283-1.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"146,147,148,149,150,151,152,153,154\" style=\"none\" lightbox_image_size=\"original\" type=\"slider\" col_spacing=\"large\" columns=\"7\" columns__sm=\"3\" columns__md=\"5\" text_align=\"center\" \/>                                                              <\/div>\n              <div class=\"box-text text-center\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n            <\/a>          <\/div>\n         <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":167,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":1048,"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/pages\/22\/revisions\/1048"}],"wp:attachment":[{"href":"https:\/\/dentalifeco.com\/en\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}